{"id":16721,"date":"2025-03-21T12:44:43","date_gmt":"2025-03-21T11:44:43","guid":{"rendered":"https:\/\/roig.zds.es\/alquiler-de-coches-en-cala-millor\/"},"modified":"2025-06-20T09:14:41","modified_gmt":"2025-06-20T07:14:41","slug":"louer-une-voiture-a-cala-millor","status":"publish","type":"page","link":"https:\/\/roig.com\/fr\/louer-une-voiture-a-cala-millor\/","title":{"rendered":"Location de voitures \u00e0 Cala Millor"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"16721\" class=\"elementor elementor-16721 elementor-12943\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-496e489 e-flex e-con-boxed e-con e-parent\" data-id=\"496e489\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1303efc elementor-widget elementor-widget-heading\" data-id=\"1303efc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Location de voitures \u00e0 Cala Millor<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e4433ff e-flex e-con-boxed e-con e-parent\" data-id=\"e4433ff\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5e19047 elementor-widget elementor-widget-text-editor\" data-id=\"5e19047\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Si vous souhaitez <strong>louer une voiture pr\u00e8s de Cala Millor<\/strong> pour vos prochaines vacances \u00e0 Majorque, <strong>ROIG Mobility &amp; Experiences<\/strong> vous offre tout ce dont vous avez besoin. Forts d\u2019une solide exp\u00e9rience depuis 1953, nous sommes la seule entreprise des Bal\u00e9ares \u00e0 proposer un service complet de transport de voyageurs par route.  <\/p>\n<p>En plus de la location de voitures, qui vous permettra de vous d\u00e9placer librement sur l\u2019\u00eele gr\u00e2ce \u00e0 une flotte de v\u00e9hicules neufs renouvel\u00e9e chaque ann\u00e9e, nous proposons \u00e9galement des services de voitures de luxe, avec ou sans chauffeur, ainsi que des autocars, pour vous emmener sur l\u2019itin\u00e9raire de votre choix, sur mesure ou pour effectuer les excursions qui vous font envie.<\/p>\n<p>D\u00e9couvrez tous les avantages que nos <strong>voitures de location \u00e0 Cala Millor<\/strong> peuvent vous offrir. Dans notre bureau d\u2019Alcudia, vous trouverez votre agence de location de confiance. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5b6ac05 e-flex e-con-boxed e-con e-parent\" data-id=\"5b6ac05\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1446522 e-con-full e-flex e-con e-child\" data-id=\"1446522\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-22649d6 elementor-widget elementor-widget-image\" data-id=\"22649d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"319\" src=\"https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Cala-dOr-04-620x330_c-1-600x319.jpg.webp\" class=\"attachment-large size-large wp-image-12301\" alt=\"\" srcset=\"https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Cala-dOr-04-620x330_c-1-600x319.jpg.webp 600w, https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Cala-dOr-04-620x330_c-1-600x319.jpg-300x160.webp 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-008cbd1 elementor-widget elementor-widget-image\" data-id=\"008cbd1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"252\" src=\"https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Cala-Santanyi-768x323-1-600x252.jpg.webp\" class=\"attachment-large size-large wp-image-12309\" alt=\"\" srcset=\"https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Cala-Santanyi-768x323-1-600x252.jpg.webp 600w, https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Cala-Santanyi-768x323-1-600x252.jpg-300x126.webp 300w\" sizes=\"(max-width: 600px) 100vw, 600px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e046b54 e-con-full e-flex e-con e-child\" data-id=\"e046b54\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d9a58a8 elementor-widget elementor-widget-heading\" data-id=\"d9a58a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Que voir \u00e0 Cala Millor<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9158d62 elementor-widget elementor-widget-text-editor\" data-id=\"9158d62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cala Millor est une localit\u00e9 c\u00f4ti\u00e8re situ\u00e9e au nord-est de Majorque, entre Sant Lloren\u00e7 des Cardassar et Son Servera. Elle offre de nombreuses possibilit\u00e9s pour profiter pleinement de vacances compl\u00e8tes et inoubliables.  <\/p>\n<p>En ce qui concerne le tourisme baln\u00e9aire, la <strong>plage de Cala Millor<\/strong> est un grand atout pour les visiteurs. Sa longueur de pr\u00e8s de 2 kilom\u00e8tres, ses eaux cristallines et peu profondes en font la plage id\u00e9ale pour des vacances en famille, en particulier avec des enfants. <\/p>\n<p>Nous souhaitons \u00e9galement mentionner la plage de Cala Bona, la plus c\u00e9l\u00e8bre de toute la r\u00e9gion de Cala Millor. Facile d\u2019acc\u00e8s, avec un parking gratuit et une large offre de chiringuitos et de restaurants, c\u2019est l\u2019option id\u00e9ale pour passer une excellente journ\u00e9e \u00e0 la plage. De plus, cette plage abrite un grand port \u2013 le <strong>port de p\u00eache de Cala Bona<\/strong> \u2013 parfait pour profiter de la vue, de la gastronomie locale et de son incroyable coucher de soleil.   <\/p>\n<p>Le <strong>site naturel de Punta d\u2019Amer<\/strong> est une petite p\u00e9ninsule d\u2019une grande valeur \u00e9cologique, compos\u00e9e de vastes dunes, de pin\u00e8des et de formations rocheuses. Vous pourrez y profiter d\u2019une magnifique vue panoramique sur la r\u00e9gion et d\u00e9couvrir un environnement naturel unique et privil\u00e9gi\u00e9, en explorant la flore autochtone de l\u2019\u00eele. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-75c695c e-flex e-con-boxed e-con e-parent\" data-id=\"75c695c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-74863d0 e-con-full e-flex e-con e-child\" data-id=\"74863d0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bbcd5d7 elementor-widget elementor-widget-heading\" data-id=\"bbcd5d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">BUREAUX<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-505c0b3 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"505c0b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Trouve le bureau qui correspond le mieux \u00e0 ton voyage.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-831ebed elementor-widget elementor-widget-text-editor\" data-id=\"831ebed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vivez les meilleures exp\u00e9riences :<br \/>Compl\u00e9tez votre voyage en profitant de la partie la plus aventureuse de Majorque.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ac642d8 e-flex e-con-boxed e-con e-parent\" data-id=\"ac642d8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8be5681 e-con-full e-flex e-con e-child\" data-id=\"8be5681\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e60055 elementor-absolute elementor-widget elementor-widget-jet-smart-filters-checkboxes\" data-id=\"8e60055\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"jet-smart-filters-checkboxes.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-smart-filters-checkboxes jet-filter \" data-indexer-rule=\"show\" data-show-counter=\"\" data-change-counter=\"always\"><div class=\"jet-checkboxes-list\" data-query-type=\"tax_query\" data-query-var=\"services\" data-smart-filter=\"checkboxes\" data-filter-id=\"9458\" data-apply-type=\"ajax\" data-content-provider=\"jet-engine-maps\" data-additional-providers=\"[&quot;jet-engine\\\/store-list&quot;]\" data-query-id=\"store-list\" data-active-label=\"\" data-layout-options=\"{&quot;show_label&quot;:&quot;&quot;,&quot;display_options&quot;:{&quot;show_items_label&quot;:false,&quot;show_decorator&quot;:false,&quot;filter_image_size&quot;:&quot;full&quot;,&quot;show_counter&quot;:false}}\" data-query-var-suffix=\"\" data-apply-on=\"value\"><fieldset class=\"jet-checkboxes-list-wrapper\"><legend style=\"display:none;\">Services &#8211; Stores<\/legend><div class=\"jet-checkboxes-list__row jet-filter-row\">\n\t\t<label class=\"jet-checkboxes-list__item\" >\n\t\t<input\n\t\t\ttype=\"checkbox\"\n\t\t\tclass=\"jet-checkboxes-list__input\"\n\t\t\tname=\"services\"\n\t\t\tvalue=\"427\"\n\t\t\tdata-label=\"Experiences\"\n\t\t\t\t\t\taria-label=\"Experiences\"\n\t\t\t\t\t>\n\t\t<div class=\"jet-checkboxes-list__button\">\n\t\t\t\t\t\t<span class=\"jet-checkboxes-list__label\">Experiences<\/span>\n\t\t\t\t\t<\/div>\n\t<\/label>\n<\/div><div class=\"jet-checkboxes-list__row jet-filter-row\">\n\t\t<label class=\"jet-checkboxes-list__item\" >\n\t\t<input\n\t\t\ttype=\"checkbox\"\n\t\t\tclass=\"jet-checkboxes-list__input\"\n\t\t\tname=\"services\"\n\t\t\tvalue=\"397\"\n\t\t\tdata-label=\"Location de voiture\"\n\t\t\t\t\t\taria-label=\"Location de voiture\"\n\t\t\t\t\t>\n\t\t<div class=\"jet-checkboxes-list__button\">\n\t\t\t\t\t\t<span class=\"jet-checkboxes-list__label\">Location de voiture<\/span>\n\t\t\t\t\t<\/div>\n\t<\/label>\n<\/div><div class=\"jet-checkboxes-list__row jet-filter-row\">\n\t\t<label class=\"jet-checkboxes-list__item\" >\n\t\t<input\n\t\t\ttype=\"checkbox\"\n\t\t\tclass=\"jet-checkboxes-list__input\"\n\t\t\tname=\"services\"\n\t\t\tvalue=\"399\"\n\t\t\tdata-label=\"Transfer\"\n\t\t\t\t\t\taria-label=\"Transfer\"\n\t\t\t\t\t>\n\t\t<div class=\"jet-checkboxes-list__button\">\n\t\t\t\t\t\t<span class=\"jet-checkboxes-list__label\">Transfer<\/span>\n\t\t\t\t\t<\/div>\n\t<\/label>\n<\/div><\/fieldset><\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d37223a elementor-widget elementor-widget-jet-engine-maps-listing\" data-id=\"d37223a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-engine-maps-listing.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-map-listing jet-listing-grid--9490 google-provider\" data-init=\"{&quot;zoomControl&quot;:false,&quot;fullscreenControl&quot;:false,&quot;streetViewControl&quot;:false,&quot;mapTypeControl&quot;:false}\" data-markers=\"[{&quot;id&quot;:17938,&quot;latLang&quot;:{&quot;lat&quot;:&quot;39.53576840289505&quot;,&quot;lng&quot;:&quot;2.7358541762701996&quot;},&quot;label&quot;:&quot;Politique Son Oms&quot;,&quot;custom_marker&quot;:false,&quot;geo_query_distance&quot;:-1},{&quot;id&quot;:17940,&quot;latLang&quot;:{&quot;lat&quot;:&quot;39.41223268427063&quot;,&quot;lng&quot;:&quot;3.2597468828541274&quot;},&quot;label&quot;:&quot;Porto Colom&quot;,&quot;custom_marker&quot;:false,&quot;geo_query_distance&quot;:-1},{&quot;id&quot;:17944,&quot;latLang&quot;:{&quot;lat&quot;:&quot;39.46218632220666&quot;,&quot;lng&quot;:&quot;3.2777445675136785&quot;},&quot;label&quot;:&quot;Calas de Mallorca&quot;,&quot;custom_marker&quot;:false,&quot;geo_query_distance&quot;:-1},{&quot;id&quot;:17948,&quot;latLang&quot;:{&quot;lat&quot;:&quot;39.83133771185023&quot;,&quot;lng&quot;:&quot;3.1084698963174646&quot;},&quot;label&quot;:&quot;Alc\\u00fadia&quot;,&quot;custom_marker&quot;:false,&quot;geo_query_distance&quot;:-1},{&quot;id&quot;:17954,&quot;latLang&quot;:{&quot;lat&quot;:&quot;39.59121849121493&quot;,&quot;lng&quot;:&quot;3.3838803124133783&quot;},&quot;label&quot;:&quot;Cala Millor&quot;,&quot;custom_marker&quot;:false,&quot;geo_query_distance&quot;:-1},{&quot;id&quot;:17956,&quot;latLang&quot;:{&quot;lat&quot;:&quot;39.537215981220825&quot;,&quot;lng&quot;:&quot;2.7389450155374413&quot;},&quot;label&quot;:&quot;A\\u00e9roport&quot;,&quot;custom_marker&quot;:false,&quot;geo_query_distance&quot;:-1},{&quot;id&quot;:17960,&quot;latLang&quot;:{&quot;lat&quot;:&quot;39.379080532172644&quot;,&quot;lng&quot;:&quot;3.2270840133043643&quot;},&quot;label&quot;:&quot;Cala d`Or&quot;,&quot;custom_marker&quot;:false,&quot;geo_query_distance&quot;:-1}]\" data-general=\"{&quot;api&quot;:&quot;https:\\\/\\\/roig.com\\\/fr\\\/wp-json\\\/jet-engine\\\/v2\\\/get-map-marker-info\\\/&quot;,&quot;restNonce&quot;:&quot;cd2dbd2f85&quot;,&quot;listingID&quot;:9490,&quot;source&quot;:&quot;posts&quot;,&quot;width&quot;:320,&quot;offset&quot;:40,&quot;clustererImg&quot;:&quot;https:\\\/\\\/roig.com\\\/wp-content\\\/plugins\\\/jet-engine\\\/includes\\\/modules\\\/maps-listings\\\/assets\\\/lib\\\/markerclustererplus\\\/img\\\/m&quot;,&quot;marker&quot;:{&quot;type&quot;:&quot;text&quot;,&quot;html&quot;:&quot;&lt;div class=\\&quot; jet-map-marker-wrap\\&quot; style=\\&quot;cursor: pointer;\\&quot;&gt;_marker_label_&lt;\\\/div&gt;&quot;},&quot;autoCenter&quot;:false,&quot;maxZoom&quot;:10,&quot;minZoom&quot;:10,&quot;customCenter&quot;:{&quot;lat&quot;:39.6952629,&quot;lng&quot;:3.0175712},&quot;customZoom&quot;:10,&quot;popupPreloader&quot;:false,&quot;querySeparator&quot;:&quot;?&quot;,&quot;markerClustering&quot;:false,&quot;customClusterImg&quot;:[],&quot;clusterMaxZoom&quot;:&quot;&quot;,&quot;clusterRadius&quot;:&quot;&quot;,&quot;popupOpenOn&quot;:&quot;click&quot;,&quot;centeringOnOpen&quot;:true,&quot;zoomOnOpen&quot;:10,&quot;advanced&quot;:{&quot;zoom_control&quot;:&quot;auto&quot;},&quot;user_location_enabled&quot;:false,&quot;user_location_marker&quot;:false,&quot;user_location_label&quot;:&quot;&quot;,&quot;styles&quot;:[{&quot;elementType&quot;:&quot;geometry&quot;,&quot;stylers&quot;:[{&quot;color&quot;:&quot;#f5f5f5&quot;}]},{&quot;elementType&quot;:&quot;labels&quot;,&quot;stylers&quot;:[{&quot;visibility&quot;:&quot;off&quot;}]},{&quot;elementType&quot;:&quot;labels.icon&quot;,&quot;stylers&quot;:[{&quot;visibility&quot;:&quot;off&quot;}]},{&quot;elementType&quot;:&quot;labels.text.fill&quot;,&quot;stylers&quot;:[{&quot;color&quot;:&quot;#616161&quot;}]},{&quot;elementType&quot;:&quot;labels.text.stroke&quot;,&quot;stylers&quot;:[{&quot;color&quot;:&quot;#f5f5f5&quot;}]},{&quot;featureType&quot;:&quot;administrative&quot;,&quot;elementType&quot;:&quot;geometry&quot;,&quot;stylers&quot;:[{&quot;visibility&quot;:&quot;off&quot;}]},{&quot;featureType&quot;:&quot;administrative.country&quot;,&quot;elementType&quot;:&quot;geometry.fill&quot;,&quot;stylers&quot;:[{&quot;color&quot;:&quot;#e1e1e1&quot;}]},{&quot;featureType&quot;:&quot;administrative.land_parcel&quot;,&quot;stylers&quot;:[{&quot;visibility&quot;:&quot;off&quot;}]},{&quot;featureType&quot;:&quot;administrative.land_parcel&quot;,&quot;elementType&quot;:&quot;labels.text.fill&quot;,&quot;stylers&quot;:[{&quot;color&quot;:&quot;#bdbdbd&quot;}]},{&quot;featureType&quot;:&quot;administrative.neighborhood&quot;,&quot;stylers&quot;:[{&quot;visibility&quot;:&quot;off&quot;}]},{&quot;featureType&quot;:&quot;administrative.province&quot;,&quot;elementType&quot;:&quot;geometry.fill&quot;,&quot;stylers&quot;:[{&quot;color&quot;:&quot;#e1e1e1&quot;}]},{&quot;featureType&quot;:&quot;landscape&quot;,&quot;elementType&quot;:&quot;geometry.fill&quot;,&quot;stylers&quot;:[{&quot;color&quot;:&quot;#e1e1e1&quot;}]},{&quot;featureType&quot;:&quot;poi&quot;,&quot;stylers&quot;:[{&quot;visibility&quot;:&quot;off&quot;}]},{&quot;featureType&quot;:&quot;poi&quot;,&quot;elementType&quot;:&quot;geometry&quot;,&quot;stylers&quot;:[{&quot;color&quot;:&quot;#eeeeee&quot;}]},{&quot;featureType&quot;:&quot;poi&quot;,&quot;elementType&quot;:&quot;labels.text.fill&quot;,&quot;stylers&quot;:[{&quot;color&quot;:&quot;#757575&quot;}]},{&quot;featureType&quot;:&quot;poi.park&quot;,&quot;elementType&quot;:&quot;geometry&quot;,&quot;stylers&quot;:[{&quot;color&quot;:&quot;#e5e5e5&quot;}]},{&quot;featureType&quot;:&quot;poi.park&quot;,&quot;elementType&quot;:&quot;labels.text.fill&quot;,&quot;stylers&quot;:[{&quot;color&quot;:&quot;#9e9e9e&quot;}]},{&quot;featureType&quot;:&quot;road&quot;,&quot;stylers&quot;:[{&quot;visibility&quot;:&quot;off&quot;}]},{&quot;featureType&quot;:&quot;road&quot;,&quot;elementType&quot;:&quot;geometry&quot;,&quot;stylers&quot;:[{&quot;color&quot;:&quot;#ffffff&quot;}]},{&quot;featureType&quot;:&quot;road&quot;,&quot;elementType&quot;:&quot;labels.icon&quot;,&quot;stylers&quot;:[{&quot;visibility&quot;:&quot;off&quot;}]},{&quot;featureType&quot;:&quot;road.arterial&quot;,&quot;elementType&quot;:&quot;labels.text.fill&quot;,&quot;stylers&quot;:[{&quot;color&quot;:&quot;#757575&quot;}]},{&quot;featureType&quot;:&quot;road.highway&quot;,&quot;elementType&quot;:&quot;geometry&quot;,&quot;stylers&quot;:[{&quot;color&quot;:&quot;#dadada&quot;}]},{&quot;featureType&quot;:&quot;road.highway&quot;,&quot;elementType&quot;:&quot;labels.text.fill&quot;,&quot;stylers&quot;:[{&quot;color&quot;:&quot;#616161&quot;}]},{&quot;featureType&quot;:&quot;road.local&quot;,&quot;elementType&quot;:&quot;labels.text.fill&quot;,&quot;stylers&quot;:[{&quot;color&quot;:&quot;#9e9e9e&quot;}]},{&quot;featureType&quot;:&quot;transit&quot;,&quot;stylers&quot;:[{&quot;visibility&quot;:&quot;off&quot;}]},{&quot;featureType&quot;:&quot;transit.line&quot;,&quot;elementType&quot;:&quot;geometry&quot;,&quot;stylers&quot;:[{&quot;color&quot;:&quot;#e5e5e5&quot;}]},{&quot;featureType&quot;:&quot;transit.station&quot;,&quot;elementType&quot;:&quot;geometry&quot;,&quot;stylers&quot;:[{&quot;color&quot;:&quot;#eeeeee&quot;}]},{&quot;featureType&quot;:&quot;water&quot;,&quot;elementType&quot;:&quot;geometry&quot;,&quot;stylers&quot;:[{&quot;color&quot;:&quot;#c9c9c9&quot;}]},{&quot;featureType&quot;:&quot;water&quot;,&quot;elementType&quot;:&quot;geometry.fill&quot;,&quot;stylers&quot;:[{&quot;color&quot;:&quot;#f6f6f6&quot;}]},{&quot;featureType&quot;:&quot;water&quot;,&quot;elementType&quot;:&quot;labels.text.fill&quot;,&quot;stylers&quot;:[{&quot;color&quot;:&quot;#9e9e9e&quot;}]}]}\" data-listing-source=\"query\" data-query-id=\"2\" data-queried-id=\"16721|WP_Post\"><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ab8343e e-con-full e-flex e-con e-child\" data-id=\"ab8343e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c996376 elementor-widget elementor-widget-jet-listing-grid\" data-id=\"c996376\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns&quot;:&quot;1&quot;}\" data-widget_type=\"jet-listing-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-listing-grid jet-listing\"><div class=\"jet-listing-grid__items grid-col-desk-1 grid-col-tablet-1 grid-col-mobile-1 jet-listing-grid--9490 grid-collapse-gap\" data-queried-id=\"16721|WP_Post\" data-nav=\"{&quot;enabled&quot;:false,&quot;type&quot;:null,&quot;more_el&quot;:null,&quot;query&quot;:[],&quot;widget_settings&quot;:{&quot;lisitng_id&quot;:9490,&quot;posts_num&quot;:6,&quot;columns&quot;:1,&quot;columns_tablet&quot;:1,&quot;columns_mobile&quot;:1,&quot;column_min_width&quot;:240,&quot;column_min_width_tablet&quot;:240,&quot;column_min_width_mobile&quot;:240,&quot;inline_columns_css&quot;:false,&quot;is_archive_template&quot;:&quot;&quot;,&quot;post_status&quot;:[&quot;publish&quot;],&quot;use_random_posts_num&quot;:&quot;&quot;,&quot;max_posts_num&quot;:9,&quot;not_found_message&quot;:&quot;Aucun point de vente trouv\\u00e9&quot;,&quot;is_masonry&quot;:false,&quot;equal_columns_height&quot;:&quot;&quot;,&quot;use_load_more&quot;:&quot;&quot;,&quot;load_more_id&quot;:&quot;&quot;,&quot;load_more_type&quot;:&quot;click&quot;,&quot;load_more_offset&quot;:null,&quot;use_custom_post_types&quot;:&quot;&quot;,&quot;custom_post_types&quot;:[],&quot;hide_widget_if&quot;:&quot;&quot;,&quot;carousel_enabled&quot;:&quot;&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;arrows&quot;:&quot;true&quot;,&quot;arrow_icon&quot;:&quot;fa fa-angle-left&quot;,&quot;dots&quot;:&quot;&quot;,&quot;autoplay&quot;:&quot;true&quot;,&quot;pause_on_hover&quot;:&quot;true&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;true&quot;,&quot;center_mode&quot;:&quot;&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500,&quot;inject_alternative_items&quot;:&quot;&quot;,&quot;injection_items&quot;:[],&quot;scroll_slider_enabled&quot;:&quot;&quot;,&quot;scroll_slider_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;custom_query&quot;:&quot;yes&quot;,&quot;custom_query_id&quot;:&quot;2&quot;,&quot;_element_id&quot;:&quot;&quot;,&quot;collapse_first_last_gap&quot;:&quot;true&quot;,&quot;list_tag_selection&quot;:&quot;&quot;,&quot;list_items_wrapper_tag&quot;:&quot;div&quot;,&quot;list_item_tag&quot;:&quot;div&quot;,&quot;empty_items_wrapper_tag&quot;:&quot;div&quot;}}\" data-page=\"1\" data-pages=\"1\" data-listing-source=\"query\" data-listing-id=\"9490\" data-query-id=\"2\"><div class=\"jet-listing-grid__item jet-listing-dynamic-post-17938\" data-post-id=\"17938\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"9490\" class=\"elementor elementor-9490\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70aced5 e-con-full e-flex e-con e-parent\" data-id=\"70aced5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-3ceec2f e-con-full e-flex e-con e-child\" data-id=\"3ceec2f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ef71371 elementor-widget elementor-widget-heading\" data-id=\"ef71371\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Politique Son Oms<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a2d21f elementor-widget elementor-widget-text-editor\" data-id=\"5a2d21f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tCarrer del Canal de Sant Jordi, 7\nPol\u00edgono Son Oms, Palma, 07199\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dce6872 elementor-widget elementor-widget-jet-listing-dynamic-terms\" data-id=\"dce6872\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-listing-dynamic-terms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-listing jet-listing-dynamic-terms\"><span class=\"jet-listing-dynamic-terms__link\">Location de voiture<\/span><span class=\"jet-listing-dynamic-terms__delimiter\">,<\/span> <span class=\"jet-listing-dynamic-terms__link\">Transfer<\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d611e44 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"d611e44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"971\" src=\"https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Son-oms-1-844x1024.webp\" class=\"attachment-large size-large wp-image-22407\" alt=\"\" srcset=\"https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Son-oms-1-844x1024.webp 844w, https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Son-oms-1-247x300.webp 247w, https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Son-oms-1-768x931.webp 768w, https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Son-oms-1-1267x1536.webp 1267w, https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Son-oms-1.webp 1500w\" sizes=\"(max-width: 800px) 100vw, 800px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-17940\" data-post-id=\"17940\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"9490\" class=\"elementor elementor-9490\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70aced5 e-con-full e-flex e-con e-parent\" data-id=\"70aced5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-3ceec2f e-con-full e-flex e-con e-child\" data-id=\"3ceec2f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ef71371 elementor-widget elementor-widget-heading\" data-id=\"ef71371\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Porto Colom<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a2d21f elementor-widget elementor-widget-text-editor\" data-id=\"5a2d21f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tC\/ Cala Mar\u00e7al, 18\nPorto Colom, 07669\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dce6872 elementor-widget elementor-widget-jet-listing-dynamic-terms\" data-id=\"dce6872\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-listing-dynamic-terms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-listing jet-listing-dynamic-terms\"><span class=\"jet-listing-dynamic-terms__link\">Experiences<\/span><span class=\"jet-listing-dynamic-terms__delimiter\">,<\/span> <span class=\"jet-listing-dynamic-terms__link\">Location de voiture<\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d611e44 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"d611e44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Porto-Colom-1024x683.jpg\" class=\"attachment-large size-large wp-image-22391\" alt=\"\" srcset=\"https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Porto-Colom-1024x683.jpg 1024w, https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Porto-Colom-300x200.jpg 300w, https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Porto-Colom-768x512.jpg 768w, https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Porto-Colom-1536x1024.jpg 1536w, https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Porto-Colom.jpg 1920w\" sizes=\"(max-width: 800px) 100vw, 800px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-17944\" data-post-id=\"17944\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"9490\" class=\"elementor elementor-9490\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70aced5 e-con-full e-flex e-con e-parent\" data-id=\"70aced5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-3ceec2f e-con-full e-flex e-con e-child\" data-id=\"3ceec2f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ef71371 elementor-widget elementor-widget-heading\" data-id=\"ef71371\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Calas de Mallorca<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a2d21f elementor-widget elementor-widget-text-editor\" data-id=\"5a2d21f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tC\/ Passeig de Manacor 133\nCalas de Mallorca, 07689\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dce6872 elementor-widget elementor-widget-jet-listing-dynamic-terms\" data-id=\"dce6872\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-listing-dynamic-terms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-listing jet-listing-dynamic-terms\"><span class=\"jet-listing-dynamic-terms__link\">Experiences<\/span><span class=\"jet-listing-dynamic-terms__delimiter\">,<\/span> <span class=\"jet-listing-dynamic-terms__link\">Location de voiture<\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d611e44 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"d611e44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"448\" src=\"https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Calas-de-Mallorca-1-1024x573.webp\" class=\"attachment-large size-large wp-image-22402\" alt=\"\" srcset=\"https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Calas-de-Mallorca-1-1024x573.webp 1024w, https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Calas-de-Mallorca-1-300x168.webp 300w, https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Calas-de-Mallorca-1-768x430.webp 768w, https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Calas-de-Mallorca-1.webp 1068w\" sizes=\"(max-width: 800px) 100vw, 800px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-17948\" data-post-id=\"17948\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"9490\" class=\"elementor elementor-9490\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70aced5 e-con-full e-flex e-con e-parent\" data-id=\"70aced5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-3ceec2f e-con-full e-flex e-con e-child\" data-id=\"3ceec2f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ef71371 elementor-widget elementor-widget-heading\" data-id=\"ef71371\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Alc\u00fadia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a2d21f elementor-widget elementor-widget-text-editor\" data-id=\"5a2d21f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tAvenida de Pere Mas i Reus, 34, local 4\nAlc\u00fadia, Illes Balears\n07400\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dce6872 elementor-widget elementor-widget-jet-listing-dynamic-terms\" data-id=\"dce6872\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-listing-dynamic-terms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-listing jet-listing-dynamic-terms\"><span class=\"jet-listing-dynamic-terms__link\">Location de voiture<\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d611e44 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"d611e44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Alcudia-1024x768.jpg\" class=\"attachment-large size-large wp-image-22386\" alt=\"\" srcset=\"https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Alcudia-1024x768.jpg 1024w, https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Alcudia-300x225.jpg 300w, https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Alcudia-768x576.jpg 768w, https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Alcudia.jpg 1400w\" sizes=\"(max-width: 800px) 100vw, 800px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-17954\" data-post-id=\"17954\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"9490\" class=\"elementor elementor-9490\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70aced5 e-con-full e-flex e-con e-parent\" data-id=\"70aced5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-3ceec2f e-con-full e-flex e-con e-child\" data-id=\"3ceec2f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ef71371 elementor-widget elementor-widget-heading\" data-id=\"ef71371\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cala Millor<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a2d21f elementor-widget elementor-widget-text-editor\" data-id=\"5a2d21f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tAvenida de Sa Coma, 41\r\nCala Millor\r\n07560 \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dce6872 elementor-widget elementor-widget-jet-listing-dynamic-terms\" data-id=\"dce6872\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-listing-dynamic-terms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-listing jet-listing-dynamic-terms\"><span class=\"jet-listing-dynamic-terms__link\">Location de voiture<\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d611e44 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"d611e44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Cala-Millor-1024x576.jpg\" class=\"attachment-large size-large wp-image-22381\" alt=\"\" srcset=\"https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Cala-Millor-1024x576.jpg 1024w, https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Cala-Millor-300x169.jpg 300w, https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Cala-Millor-768x432.jpg 768w, https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Cala-Millor.jpg 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-17956\" data-post-id=\"17956\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"9490\" class=\"elementor elementor-9490\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70aced5 e-con-full e-flex e-con e-parent\" data-id=\"70aced5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-3ceec2f e-con-full e-flex e-con e-child\" data-id=\"3ceec2f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ef71371 elementor-widget elementor-widget-heading\" data-id=\"ef71371\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">A\u00e9roport<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a2d21f elementor-widget elementor-widget-text-editor\" data-id=\"5a2d21f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tCarrer del Canal de Sant Jordi, 7, Llevant, 07199 Palma, Illes Balears, Espagne\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dce6872 elementor-widget elementor-widget-jet-listing-dynamic-terms\" data-id=\"dce6872\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-listing-dynamic-terms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-listing jet-listing-dynamic-terms\"><span class=\"jet-listing-dynamic-terms__link\">Location de voiture<\/span><span class=\"jet-listing-dynamic-terms__delimiter\">,<\/span> <span class=\"jet-listing-dynamic-terms__link\">Transfer<\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d611e44 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"d611e44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Aeropuerto-1024x682.jpg\" class=\"attachment-large size-large wp-image-22376\" alt=\"\" srcset=\"https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Aeropuerto-1024x682.jpg 1024w, https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Aeropuerto-300x200.jpg 300w, https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Aeropuerto-768x512.jpg 768w, https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Aeropuerto.jpg 1280w\" sizes=\"(max-width: 800px) 100vw, 800px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"jet-listing-grid__item jet-listing-dynamic-post-17960\" data-post-id=\"17960\"  >\t\t<div data-elementor-type=\"jet-listing-items\" data-elementor-id=\"9490\" class=\"elementor elementor-9490\" data-elementor-post-type=\"jet-engine\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70aced5 e-con-full e-flex e-con e-parent\" data-id=\"70aced5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-3ceec2f e-con-full e-flex e-con e-child\" data-id=\"3ceec2f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ef71371 elementor-widget elementor-widget-heading\" data-id=\"ef71371\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cala d`Or<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a2d21f elementor-widget elementor-widget-text-editor\" data-id=\"5a2d21f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tAv. dels Benvinguts, 64, 07660 Cala D&rsquo;or, Illes Balears, Espagne\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dce6872 elementor-widget elementor-widget-jet-listing-dynamic-terms\" data-id=\"dce6872\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-listing-dynamic-terms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"jet-listing jet-listing-dynamic-terms\"><span class=\"jet-listing-dynamic-terms__link\">Experiences<\/span><span class=\"jet-listing-dynamic-terms__delimiter\">,<\/span> <span class=\"jet-listing-dynamic-terms__link\">Location de voiture<\/span><span class=\"jet-listing-dynamic-terms__delimiter\">,<\/span> <span class=\"jet-listing-dynamic-terms__link\">Transfer<\/span><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d611e44 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"d611e44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"336\" height=\"336\" src=\"https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Cala-dor.png\" class=\"attachment-large size-large wp-image-9478\" alt=\"\" srcset=\"https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Cala-dor.png 336w, https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Cala-dor-300x300.png 300w, https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Cala-dor-150x150.png 150w\" sizes=\"(max-width: 336px) 100vw, 336px\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-79b5c52 e-flex e-con-boxed e-con e-parent\" data-id=\"79b5c52\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bb66efd elementor-widget elementor-widget-heading\" data-id=\"bb66efd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Avantages de louer une voiture \u00e0 Cala Millor avec ROIG Mobility &amp; Experiences\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e6cc780 elementor-widget elementor-widget-text-editor\" data-id=\"e6cc780\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Si vous souhaitez visiter ces lieux et bien d\u2019autres encore, n\u2019h\u00e9sitez pas \u00e0 louer une voiture \u00e0 Cala Millor avec ROIG Mobility &amp; Experiences \u2013 au meilleur prix et avec de nombreux avantages : second conducteur sans frais suppl\u00e9mentaires, annulation gratuite, flotte renouvel\u00e9e chaque ann\u00e9e\u2026<\/p>\n<p>Pour plus d\u2019informations sur nos services, n\u2019h\u00e9sitez pas \u00e0 nous appeler au <a href=\"tel:(+34)%20971%2065%2071%2073\">(+34) 971 65 71 73<\/a>, de 8h00 \u00e0 20h00 sans interruption, ou \u00e0 nous envoyer un e-mail \u00e0 l\u2019adresse suivante : <a href=\"mailto:info@roig.com\">info@roig.com<\/a>. Nous vous contacterons dans les plus brefs d\u00e9lais. <\/p>\n<p>Nous proposons la meilleure location de voitures \u00e0 Cala Millor, avec ou sans chauffeur \u2013 ne te contente pas d\u2019en entendre parler, viens vivre une escapade unique \u00e0 Majorque ! Avec ROIG Mobility &amp; Experiences, toute l\u2019\u00eele est \u00e0 port\u00e9e de main. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fd2f847 e-flex e-con-boxed e-con e-parent\" data-id=\"fd2f847\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6a6d6f8 e-con-full e-flex e-con e-child\" data-id=\"6a6d6f8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7164738 e-con-full e-flex e-con e-child\" data-id=\"7164738\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ee2e0ca elementor-widget elementor-widget-heading\" data-id=\"ee2e0ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">R\u00e9servez votre voiture de location \u00e0 <br>Cala Millor<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a39e8a7 elementor-widget elementor-widget-text-editor\" data-id=\"a39e8a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Si vous souhaitez louer votre voiture \u00e0 Cala Millor avec nous, ou si vous avez des questions concernant nos services, appelez-nous au<strong><a href=\"tel:(+34)%20971%2065%2071%2073\"> (+34) 971 65 71 73<\/a>, de 8h00 \u00e0 20h00 sans interruption<\/strong>. Notre \u00e9quipe du service client se fera un plaisir de vous aider. Vous pouvez \u00e9galement nous contacter par e-mail en nous \u00e9crivant \u00e0 <a href=\"mailto:info@roig.com\"><strong>info@roig.com<\/strong><\/a>. Nous vous r\u00e9pondrons dans les plus brefs d\u00e9lais.   <\/p>\n<p>Pour tous ceux qui recherchent une voiture de location \u00e0 Cala Millor, ROIG Mobility &amp; Experiences est le meilleur choix. Nous sommes l\u2019entreprise leader dans le transport de personnes par route, et nous voulons que vous d\u00e9couvriez pourquoi. Nous vous attendons!  <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bb830af e-flex e-con-boxed e-con e-parent\" data-id=\"bb830af\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-14fd253 e-con-full e-flex e-con e-child\" data-id=\"14fd253\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-786cf3a elementor-widget elementor-widget-heading\" data-id=\"786cf3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">AUTRES DESTINATIONS DE LOCATION DE VOITURES<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e515671 elementor-widget elementor-widget-heading\" data-id=\"e515671\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Autres destinations de location de voitures \u00e0 Majorque<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e15c74f elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"e15c74f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chez ROIG Mobility &amp; Experiences, nous voulons vous rapprocher des meilleurs endroits \u00e0 visiter \u00e0 Majorque et vous permettre de les d\u00e9couvrir comme le fait la population locale.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cd884b9 e-con-full e-flex e-con e-child\" data-id=\"cd884b9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f7c0d40 e-con-full e-flex e-con e-parent\" data-id=\"f7c0d40\" data-element_type=\"container\" data-e-type=\"container\" id=\"textswiper\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e69a1f elementor-widget elementor-widget-jet-carousel\" data-id=\"1e69a1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show_mobile&quot;:&quot;2&quot;,&quot;slides_to_scroll_mobile&quot;:&quot;1&quot;,&quot;slides_to_show&quot;:&quot;2&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;}\" data-widget_type=\"jet-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-carousel jet-elements\"><div class=\"jet-carousel-wrap jet-equal-cols\">\n\t<div class=\"jet-carousel\" data-slider_options=\"{&quot;autoplaySpeed&quot;:5000,&quot;autoplay&quot;:false,&quot;infinite&quot;:false,&quot;centerMode&quot;:false,&quot;centerPadding&quot;:&quot;50px&quot;,&quot;pauseOnHover&quot;:false,&quot;speed&quot;:500,&quot;arrows&quot;:false,&quot;dots&quot;:false,&quot;variableWidth&quot;:false,&quot;prevArrow&quot;:&quot;.jet-carousel__prev-arrow-1e69a1f&quot;,&quot;nextArrow&quot;:&quot;.jet-carousel__next-arrow-1e69a1f&quot;,&quot;rtl&quot;:false,&quot;fractionNav&quot;:false}\" dir=\"ltr\">\n\t<div class=\"elementor-slick-slider\">\n\n<div class=\"jet-carousel__item\">\n\t<div class=\"jet-carousel__item-inner\"><a href=\"\/fr\/location-de-voiture-a-cala-dor\/\" class=\"jet-carousel__item-link\" ><img decoding=\"async\" src=\"https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Cala-dOr-04-620x330_c-1-600x319.jpg.webp\" class=\"jet-carousel__item-img\" alt=\"Cala-dOr-04-620x330_c-1-600x319.jpg\" loading=\"lazy\"><\/a><div class=\"jet-carousel__content\"><h4 class=\"jet-carousel__item-title\">Location de voitures \u00e0 Cala d'Or<\/h4><div class=\"jet-carousel__item-text\"><p>Cala d\u2019Or est la principale ville touristique de la municipalit\u00e9 de <strong>Santany\u00ed<\/strong>, situ\u00e9e sur la c\u00f4te sud-est de Majorque, au sud de Portocolom. Son emplacement dans l'une des zones les plus belles de la c\u00f4te de l'\u00eele, ainsi que sa proximit\u00e9 avec d'autres villes tr\u00e8s attractives comme Cala Ferrera, Cala Serena et Portopetro, expliquent pourquoi il vaut la peine de visiter Cala d\u2019Or.<\/p><\/div><\/div><\/div>\n<\/div>\n\n<div class=\"jet-carousel__item\">\n\t<div class=\"jet-carousel__item-inner\"><a href=\"\/fr\/location-de-voitures-a-can-pastilla\/\" class=\"jet-carousel__item-link\" ><img decoding=\"async\" src=\"https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Can-Pastilla_petit-1-620x330-1-600x319.jpg.webp\" class=\"jet-carousel__item-img\" alt=\"Can-Pastilla_petit-1-620x330-1-600x319.jpg\" loading=\"lazy\"><\/a><div class=\"jet-carousel__content\"><h4 class=\"jet-carousel__item-title\">Location de voitures \u00e0 Can Pastilla<\/h4><div class=\"jet-carousel__item-text\"><p>Can Pastilla est une ville touristique appartenant au district de Playa de Palma, reli\u00e9e \u00e0 d'autres destinations de vacances majeures telles que <strong>Les Meravelles et S'Arenal<\/strong> par une promenade de 11 km en bord de mer. Cette art\u00e8re la relie \u00e9galement \u00e0 Palma de Majorque, la capitale de l'\u00eele, via l'autoroute Ma-19. De plus, elle est tr\u00e8s proche de l'a\u00e9roport de Palma.<\/p><\/div><\/div><\/div>\n<\/div>\n\n<div class=\"jet-carousel__item\">\n\t<div class=\"jet-carousel__item-inner\"><a href=\"\/fr\/location-de-voitures-a-portocolom\/\" class=\"jet-carousel__item-link\" ><img decoding=\"async\" src=\"https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Portocolom3-620x330-1-600x319.jpg.webp\" class=\"jet-carousel__item-img\" alt=\"Portocolom3-620x330-1-600x319.jpg\" loading=\"lazy\"><\/a><div class=\"jet-carousel__content\"><h4 class=\"jet-carousel__item-title\">Location de voitures \u00e0 Portocolom<\/h4><div class=\"jet-carousel__item-text\"><p>Portocolom est une ville c\u00f4ti\u00e8re, appartenant \u00e0 la municipalit\u00e9 de <strong>Felanitx<\/strong> et situ\u00e9e dans le sud-est de Majorque. Surnomm\u00e9e Es Port par les habitants, c'est la destination de vacances <strong>pr\u00e9f\u00e9r\u00e9e des r\u00e9sidents de l'est de l'\u00eele.<\/strong><\/p><\/div><\/div><\/div>\n<\/div>\n\n<div class=\"jet-carousel__item\">\n\t<div class=\"jet-carousel__item-inner\"><a href=\"\/fr\/location-de-voitures-a-cales-de-mallorca\/\" class=\"jet-carousel__item-link\" ><img decoding=\"async\" src=\"https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Cales-Mallorca2-600x399-1.jpg.webp\" class=\"jet-carousel__item-img\" alt=\"Cales-Mallorca2-600x399-1.jpg\" loading=\"lazy\"><\/a><div class=\"jet-carousel__content\"><h4 class=\"jet-carousel__item-title\">Location de voitures \u00e0 Cales de Mallorca<\/h4><div class=\"jet-carousel__item-text\"><p>Cales de Mallorca est situ\u00e9e dans la zone c\u00f4ti\u00e8re de la finca d'Hospitalet Vell, dans la municipalit\u00e9 de <strong>Manacor.<\/strong> Il s'agit du principal centre touristique de la c\u00f4te de Manacor, ainsi qu'une destination id\u00e9ale pour ceux qui pr\u00e9voient de <strong>voyager \u00e0 Majorque avec des enfants.<\/strong><\/p><\/div><\/div><\/div>\n<\/div>\n\n<div class=\"jet-carousel__item\">\n\t<div class=\"jet-carousel__item-inner\"><a href=\"\/fr\/location-de-voiture-a-santa-ponsa\/\" class=\"jet-carousel__item-link\" ><img decoding=\"async\" src=\"https:\/\/roig.com\/wp-content\/uploads\/2024\/08\/mallorca-cala-santanyi.jpg\" class=\"jet-carousel__item-img\" alt=\"mallorca-cala-santanyi\" loading=\"lazy\"><\/a><div class=\"jet-carousel__content\"><h4 class=\"jet-carousel__item-title\">Location de voitures \u00e0 Santa Ponsa<\/h4><div class=\"jet-carousel__item-text\"><p>Ce village c\u00f4tier appartient \u00e0 la municipalit\u00e9 de Calvi\u00e0, <strong>l'une des zones pr\u00e9f\u00e9r\u00e9es des visiteurs qui choisissent de passer leurs vacances \u00e0 Majorque.<\/strong> \u00c0 seulement 20 kilom\u00e8tres de Palma de Majorque, Santa Ponsa poss\u00e8de l'une des plus longues plages de l'\u00eele, avec 1300 m\u00e8tres de longueur. Sa popularit\u00e9 est due \u00e0 sa proximit\u00e9 avec des localit\u00e9s comme Magaluf ou Can Picafort, connues pour leurs eaux cristallines.<\/p><\/div><\/div><\/div>\n<\/div>\n\n<div class=\"jet-carousel__item\">\n\t<div class=\"jet-carousel__item-inner\"><a href=\"\/fr\/location-de-voitures-au-parc-naturel-de-mondrago\/\" class=\"jet-carousel__item-link\" ><img decoding=\"async\" src=\"https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Proyecto-nuevo-7-2-600x319.jpg.webp\" class=\"jet-carousel__item-img\" alt=\"Proyecto-nuevo-7-2-600x319.jpg\" loading=\"lazy\"><\/a><div class=\"jet-carousel__content\"><h4 class=\"jet-carousel__item-title\">Location de voitures au Parc Naturel de Mondrag\u00f3<\/h4><div class=\"jet-carousel__item-text\"><p>Le <strong>Parc Naturel de Mondrag\u00f3<\/strong>, d\u00e9clar\u00e9 en 1992, est une r\u00e9serve naturelle prot\u00e9g\u00e9e. Il se situe dans la municipalit\u00e9 de Santany\u00ed et est l'une des destinations les plus visit\u00e9es de Majorque. Sa combinaison de flore et de faune caract\u00e9ristiques de la r\u00e9gion forme des paysages uniques qui m\u00ealent mer et montagne.<\/p><\/div><\/div><\/div>\n<\/div>\n\n<div class=\"jet-carousel__item\">\n\t<div class=\"jet-carousel__item-inner\"><a href=\"\/fr\/location-de-voitures-a-cala-varques\/\" class=\"jet-carousel__item-link\" ><img decoding=\"async\" src=\"https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Proyecto-nuevo-7-copia-1-600x319.jpg.webp\" class=\"jet-carousel__item-img\" alt=\"Proyecto-nuevo-7-copia-1-600x319.jpg\" loading=\"lazy\"><\/a><div class=\"jet-carousel__content\"><h4 class=\"jet-carousel__item-title\">Location de voitures \u00e0 Cala Varques<\/h4><div class=\"jet-carousel__item-text\"><p><strong>Cala Varques<\/strong> est l'une des meilleures cales de Majorque ; une plage naturelle et vierge, avec du sable fin et blanc, d'environ 70 m\u00e8tres de longueur, et une localisation isol\u00e9e entour\u00e9e de pins et de rochers, ce qui en fait un endroit unique et digne d'\u00eatre visit\u00e9.<\/p><\/div><\/div><\/div>\n<\/div>\n\n<div class=\"jet-carousel__item\">\n\t<div class=\"jet-carousel__item-inner\"><a href=\"\/fr\/louer-une-voiture-a-alcudia\/\" class=\"jet-carousel__item-link\" ><img decoding=\"async\" src=\"https:\/\/roig.com\/wp-content\/uploads\/2025\/03\/Alcudia-Beach-Mallorca-Balearic-Islands-Spain-shutterstock_157484990-Copy-620x330-1-600x319.jpg.webp\" class=\"jet-carousel__item-img\" alt=\"Alcudia-Beach-Mallorca-Balearic-Islands-Spain-shutterstock_157484990-Copy-620x330-1-600x319.jpg\" loading=\"lazy\"><\/a><div class=\"jet-carousel__content\"><h4 class=\"jet-carousel__item-title\">Location de voitures \u00e0 Alc\u00fadia<\/h4><div class=\"jet-carousel__item-text\"><p>R\u00e9servez votre location de voiture \u00e0 <strong>Alc\u00fadia<\/strong>, o\u00f9 vous trouverez certains des plus beaux paysages de Majorque. Il s'agit d'une localit\u00e9 situ\u00e9e au nord de l'\u00eele, connue pour ses plages. Elle se distingue \u00e9galement par les <strong>remparts m\u00e9di\u00e9vaux<\/strong> de sa vieille ville, son march\u00e9 populaire et ses rues et maisons en pierre, ce qui fait de la visite d'Alc\u00fadia une exp\u00e9rience inoubliable.<\/p><\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Location de voitures \u00e0 Cala Millor Si vous souhaitez louer une voiture pr\u00e8s de Cala Millor pour vos prochaines vacances \u00e0 Majorque, ROIG Mobility &amp; Experiences vous offre tout ce dont vous avez besoin. Forts d\u2019une solide exp\u00e9rience depuis 1953, nous sommes la seule entreprise des Bal\u00e9ares \u00e0 proposer un service complet de transport de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":16149,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-16721","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/roig.com\/fr\/wp-json\/wp\/v2\/pages\/16721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roig.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/roig.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/roig.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/roig.com\/fr\/wp-json\/wp\/v2\/comments?post=16721"}],"version-history":[{"count":0,"href":"https:\/\/roig.com\/fr\/wp-json\/wp\/v2\/pages\/16721\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roig.com\/fr\/wp-json\/wp\/v2\/media\/16149"}],"wp:attachment":[{"href":"https:\/\/roig.com\/fr\/wp-json\/wp\/v2\/media?parent=16721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}