{"id":28605,"date":"2026-04-15T13:21:50","date_gmt":"2026-04-15T11:21:50","guid":{"rendered":"https:\/\/roig.com\/?post_type=experiences&#038;p=28605"},"modified":"2026-05-11T15:15:08","modified_gmt":"2026-05-11T13:15:08","slug":"tour-de-lile-de-cabrera","status":"publish","type":"experiences","link":"https:\/\/roig.com\/fr\/experiences\/tour-de-lile-de-cabrera\/","title":{"rendered":"Tour de l\u2019\u00eele de Cabrera"},"content":{"rendered":"\n<p>D\u00e9couvrez une exp\u00e9rience unique avec notre excursion en bateau \u00e0 Cabrera depuis Majorque et visitez l\u2019un des espaces naturels les mieux pr\u00e9serv\u00e9s de la M\u00e9diterran\u00e9e : le Parc National de l\u2019Archipel de Cabrera.<\/p>\n\n\n\n<p>Embarquez pour une travers\u00e9e confortable et panoramique vers cette \u00eele vierge o\u00f9 le temps semble s\u2019arr\u00eater. Une fois sur place, vous disposerez de temps libre pour explorer l\u2019\u00eele \u00e0 votre rythme, suivre des sentiers de randonn\u00e9e et d\u00e9couvrir ses paysages naturels dans un environnement prot\u00e9g\u00e9 et unique. Nous vous fournirons \u00e9galement toutes les informations n\u00e9cessaires pour profiter pleinement de votre visite.<\/p>\n\n\n\n<p>L\u2019exp\u00e9rience se termine par un arr\u00eat dans la c\u00e9l\u00e8bre Grotte Bleue de Cabrera, dont les eaux cristallines d\u2019un bleu turquoise intense offrent le cadre parfait pour une baignade en pleine nature.<\/p>\n\n\n\n<p>R\u00e9servez d\u00e8s maintenant votre excursion \u00e0 Cabrera depuis Majorque et vivez une journ\u00e9e inoubliable entre mer, nature et paysages uniques.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9vadez-vous \u00e0 Cabrera et d\u00e9couvrez un paradis cach\u00e9 en M\u00e9diterran\u00e9e. Naviguez depuis Majorque, explorez l\u2019\u00eele \u00e0 votre rythme et profitez d\u2019une baignade incroyable dans la mythique Grotte Bleue. Une exp\u00e9rience tout simplement inoubliable.<\/p>\n","protected":false},"featured_media":28147,"template":"","experience-category":[272],"class_list":["post-28605","experiences","type-experiences","status-publish","has-post-thumbnail","hentry","experience-category-mar-fr"],"_links":{"self":[{"href":"https:\/\/roig.com\/fr\/wp-json\/wp\/v2\/experiences\/28605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roig.com\/fr\/wp-json\/wp\/v2\/experiences"}],"about":[{"href":"https:\/\/roig.com\/fr\/wp-json\/wp\/v2\/types\/experiences"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roig.com\/fr\/wp-json\/wp\/v2\/media\/28147"}],"wp:attachment":[{"href":"https:\/\/roig.com\/fr\/wp-json\/wp\/v2\/media?parent=28605"}],"wp:term":[{"taxonomy":"experience-category","embeddable":true,"href":"https:\/\/roig.com\/fr\/wp-json\/wp\/v2\/experience-category?post=28605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}