{"id":7531,"date":"2022-01-25T11:21:10","date_gmt":"2022-01-25T10:21:10","guid":{"rendered":"https:\/\/roig.it-satzinger.de\/blog\/son-amar\/"},"modified":"2026-04-22T14:50:52","modified_gmt":"2026-04-22T12:50:52","slug":"son-amar","status":"publish","type":"post","link":"https:\/\/roig.com\/de\/son-amar\/","title":{"rendered":"Son Amar"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>Ausflug zum Son Amar<\/strong><\/h2>\n\n\n\n<p>M\u00f6chten Sie einen <strong>unvergesslichen Abend<\/strong> verbringen und eine der besten Shows der gr\u00f6\u00dften Balearischen Insel sehen? Verpassen Sie nicht den Ausflug zum <strong>Son Amar<\/strong>, einem alten mallorquinischen Herrenhaus in <strong>Bunyola<\/strong>, wo Sie mit Ihren Liebsten einen unvergesslichen Abend verbringen werden.<\/p>\n\n\n\n<p>In dieser <strong>unvergleichlichen Umgebung<\/strong> k\u00f6nnen Sie Ihre <strong>f\u00fcnf Sinne<\/strong> von dem verw\u00f6hnen lassen, was die Nacht bereith\u00e4lt, beginnend mit einem <strong>Abendessen<\/strong>, bei dem Sie typische K\u00f6stlichkeiten Mallorcas wie das <strong>Tombet<\/strong> kosten oder die Delikatessen des <strong>iberischen Schinkens<\/strong> genie\u00dfen k\u00f6nnen.<\/p>\n\n\n\n<p>Und wenn das Abendessen zu Ende ist, erwartet Sie eine <strong>fantastische exklusive Show<\/strong>, die sich von Jahr zu Jahr \u00e4ndert. Darin k\u00f6nnen Sie die <strong>Choreografien der Flamencot\u00e4nzer<\/strong> bewundern, die unm\u00f6glichen Kunstst\u00fccke der <strong>Akrobaten<\/strong> bestaunen, ein <strong>live spielendes Orchester<\/strong> h\u00f6ren oder mit <strong>Humoristen<\/strong> lachen, die kein gutes Haar an sich lassen. <strong>Jahrzehnte an Erfahrung<\/strong> machen die Show des Son Amar zu einer der <strong>unverzichtbaren Aktivit\u00e4ten<\/strong> w\u00e4hrend Ihres Aufenthalts auf Mallorca, mit einer Musik- und Lichtshow auf dem Niveau der <strong>besten Tanzshows weltweit<\/strong> \u2014 verpassen Sie diese Gelegenheit nicht!<\/p>\n\n\n\n<p>Dieser Ausflug zum Son Amar mit dem <strong>ROIG Busservice<\/strong> ist sowohl ideal f\u00fcr ein <strong>romantisches Abendessen zu zweit<\/strong> als auch f\u00fcr einen <strong>Familienausflug<\/strong>.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>So gelangen Sie mit dem Bus zum Son Amar<\/strong><\/h2>\n\n\n\n<p>Obwohl Sie das Anwesen mit unseren <strong>Mietwagen auf Mallorca<\/strong> erreichen k\u00f6nnen, ist eine gute Alternative der <strong>ROIG Busservice<\/strong>, der es Ihnen erm\u00f6glicht, sich um nichts anderes k\u00fcmmern zu m\u00fcssen, als eine gro\u00dfartige Zeit zu haben.<\/p>\n\n\n\n<p>Der Ausflug zum Son Amar holt Sie an Ihrem Urlaubsort ab und bringt Sie rechtzeitig zum Anwesen f\u00fcr die Show, und bringt Sie nach deren Ende wieder zu Ihrem <strong>Urlaubsziel<\/strong> zur\u00fcck. Nachfolgend werden die Abholpunkte des Busses angegeben:<\/p>\n\n\n\n<p><strong>S\u00dcDOSTEN:<\/strong> Cala Mondrag\u00f3 \u2013 Cala Barca \u2013 Cala Egos \u2013 Porto Cari \u2013 Cala D&#8217;or \u2013 Cala Ferrera \u2013 Cala Serena \u2013 Porto Colom<\/p>\n\n\n\n<p><strong>OSTEN:<\/strong> Porto Cristo \u2013 Cala Mand\u00eda \u2013 Cala Rom\u00e1ntica \u2013 Calas de Mallorca \u2013 Cala Tropicana \u2013 Cala Murada \u2013 Cala Figuera \u2013 Cala Santany\u00ed \u2013 Colonia Sant Jordi<\/p>\n\n\n\n<p>Die <strong>genauen Abholpunkte<\/strong> werden bei Ihrer Reservierung mitgeteilt.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Reservierungen f\u00fcr den Busausflug zum Son Amar<\/strong><\/h2>\n\n\n\n<p>Wenn Sie einen Ausflug zum <strong>Son Amar<\/strong> reservieren m\u00f6chten, m\u00fcssen Sie sich lediglich mit <strong>ROIG Bus<\/strong> in Verbindung setzen und dabei den <strong>gew\u00fcnschten Tag<\/strong> f\u00fcr die Show sowie die <strong>Anzahl der teilnehmenden Personen<\/strong> angeben. Teilen Sie uns auch mit, ob sich unter den Teilnehmern <strong>Minderj\u00e4hrige unter 18 Jahren<\/strong> befinden. Unser Team wird Sie \u00fcber die <strong>Bedingungen und Preise<\/strong> dieses einzigartigen Abends informieren.<\/p>\n\n\n\n<p>Rufen Sie uns an unter <strong>+34 971 65 71 73<\/strong> oder schreiben Sie uns eine <strong>E-Mail mit Ihren Daten an <a href=\"mailto:info@roig.com\">info@roig.com<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eine unvergessliche Nacht in einem mallorquinischen Gutshaus. Nach einem Abendessen mit heimischem Wein und Sekt k\u00f6nnen sie die spektakul\u00e4re Show, mit modernster Tontechnik, Licht- und Spezialeffekten, einem fantastischen spanischen Ballet und internationalen Artisten geniessen. Ein Erlebnis f\u00fcr die ganze Familie.<\/p>\n","protected":false},"author":1,"featured_media":3344,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[155,154],"tags":[62],"class_list":["post-7531","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ausfluge-mit-roig","category-mallorca-entdecken","tag-espectaculos"],"_links":{"self":[{"href":"https:\/\/roig.com\/de\/wp-json\/wp\/v2\/posts\/7531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roig.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/roig.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/roig.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/roig.com\/de\/wp-json\/wp\/v2\/comments?post=7531"}],"version-history":[{"count":1,"href":"https:\/\/roig.com\/de\/wp-json\/wp\/v2\/posts\/7531\/revisions"}],"predecessor-version":[{"id":28365,"href":"https:\/\/roig.com\/de\/wp-json\/wp\/v2\/posts\/7531\/revisions\/28365"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/roig.com\/de\/wp-json\/wp\/v2\/media\/3344"}],"wp:attachment":[{"href":"https:\/\/roig.com\/de\/wp-json\/wp\/v2\/media?parent=7531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/roig.com\/de\/wp-json\/wp\/v2\/categories?post=7531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/roig.com\/de\/wp-json\/wp\/v2\/tags?post=7531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}